{"id":37800,"date":"2024-02-15T16:03:20","date_gmt":"2024-02-15T14:03:20","guid":{"rendered":"https:\/\/sail-ingreece.com\/agents\/"},"modified":"2026-06-12T08:38:33","modified_gmt":"2026-06-12T06:38:33","slug":"agents","status":"publish","type":"page","link":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio","title":{"rendered":"Agenti"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"37800\" class=\"elementor elementor-37800 elementor-37680\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b483b4f e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"b483b4f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3efa105 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"3efa105\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30659de\" data-id=\"30659de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-253f585 elementor-widget elementor-widget-heading\" data-id=\"253f585\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prenotazioni di agenti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e06c1c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2e06c1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il nostro obiettivo \u00e8 quello di rendere il lavoro con Sail in Grecia il pi\u00f9 semplice possibile. Crediamo nella trasparenza, nell&#8217;evitare sorprese e nell&#8217;aiutare a definire le aspettative con lei e i suoi clienti. Questo ci permette di prevenire le delusioni e di avere clienti felici a bordo delle nostre navi.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26fd510 elementor-widget elementor-widget-spacer\" data-id=\"26fd510\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7321db9 elementor-widget elementor-widget-raven-button\" data-id=\"7321db9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;turn_to_popup_action_button&quot;:&quot;no&quot;}\" data-widget_type=\"raven-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\">\n\t\t\t<a class=\"raven-button raven-button-widget-normal-effect-none  raven-button-text-align-center raven-button-link elementor-animation-none\" href=\"http:\/\/popmake-37907\">\t\t\t\t<div class=\"raven-button-overlay\" ><\/div>\n\t\t\t\t<span class=\"raven-button-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"button-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"raven-button-texts-wrapper\">\n\t\t\t\t\t\t\t<div class=\"button-text\">\n\t\t\t\t\t\t\t\t<span class=\"raven-button-text\">\n\t\t\t\t\t\t\t\t\tCONTATTI\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/a>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5195946\" data-id=\"5195946\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65747e7 elementor-widget elementor-widget-spacer\" data-id=\"65747e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17e3fff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17e3fff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a4b7d5\" data-id=\"8a4b7d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3d009c elementor-widget elementor-widget-spacer\" data-id=\"e3d009c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d7351b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d7351b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-10e2c2f\" data-id=\"10e2c2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3111d4 elementor-widget elementor-widget-heading\" data-id=\"f3111d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IL SERVIZIO CLIENTI \u00c8 IMPORTANTE PER NOI.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f8ba59 elementor-widget elementor-widget-text-editor\" data-id=\"1f8ba59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPu\u00f2 essere certo che Sail Croatia fornir\u00e0 il miglior standard di servizio a lei e ai suoi clienti.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-dd54adc\" data-id=\"dd54adc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5824ce7 elementor-widget elementor-widget-heading\" data-id=\"5824ce7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PER LA NOSTRA ATTIVIT\u00c0 CI AFFIDIAMO AL PASSAPAROLA.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f933a0f elementor-widget elementor-widget-text-editor\" data-id=\"f933a0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"info__item\"><div class=\"info__item-content\"><p class=\"info__item-paragraph\">Per questo motivo, \u00e8 fondamentale mantenere elevati standard di servizio al cliente e recensioni positive. Non \u00e8 ancora convinto? Dia un&#8217;occhiata alle oltre 1.000 recensioni indipendenti su <a href=\"https:\/\/www.tripadvisor.com\/Attraction_Review-g189458-d8472257-Reviews-Sail_In_Greece-Corfu_Ionian_Islands.html\" target=\"_blank\" rel=\"noopener\">TripAdvisor<\/a>.  <\/p><\/div><\/div><div class=\"info__item\"><div class=\"info__item-content\"> <\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-deea199\" data-id=\"deea199\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e431795 elementor-widget elementor-widget-heading\" data-id=\"e431795\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MISURIAMO IL FEEDBACK DEI NOSTRI CLIENTI.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae77fbe elementor-widget elementor-widget-text-editor\" data-id=\"ae77fbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIl feedback dei clienti viene raccolto settimanalmente su ogni aspetto delle nostre crociere per mantenere la qualit\u00e0 a bordo. Caratteristiche come le prestazioni del personale, la qualit\u00e0 del cibo e le strutture della nave sono tutte monitorate attentamente per garantire il mantenimento degli standard. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4dbc819\" data-id=\"4dbc819\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b0b6c7 elementor-widget elementor-widget-heading\" data-id=\"0b0b6c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FACILIT\u00c0 DI VENDITA AI CLIENTI.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1434daa elementor-widget elementor-widget-text-editor\" data-id=\"1434daa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"info container\"><div class=\"info__section info__section--x4 d-grid\"><div class=\"info__item\"><div class=\"info__item-content\"><p class=\"info__item-paragraph\">Le informazioni sulle crociere sono disponibili online, compresi i prezzi aggiornati, le informazioni sull&#8217;itinerario e le inclusioni della crociera.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55c181c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55c181c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-cb17a16\" data-id=\"cb17a16\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2c95a9 elementor-widget elementor-widget-text-editor\" data-id=\"d2c95a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una commissione del 10% \u00e8 disponibile su Ionian Cruise!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d286642 elementor-widget elementor-widget-raven-button\" data-id=\"d286642\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;turn_to_popup_action_button&quot;:&quot;no&quot;}\" data-widget_type=\"raven-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\">\n\t\t\t<a class=\"raven-button raven-button-widget-normal-effect-none  raven-button-text-align-center raven-button-link elementor-animation-none\" href=\"https:\/\/sail-ingreece.com\/ionian-islands\/\">\t\t\t\t<div class=\"raven-button-overlay\" ><\/div>\n\t\t\t\t<span class=\"raven-button-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"button-text-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"raven-button-texts-wrapper\">\n\t\t\t\t\t\t\t<div class=\"button-text\">\n\t\t\t\t\t\t\t\t<span class=\"raven-button-text\">\n\t\t\t\t\t\t\t\t\tVISTA CROCIERA\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/a>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-558f538\" data-id=\"558f538\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e81c738\" data-id=\"e81c738\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a942dec\" data-id=\"a942dec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f680dce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f680dce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41ec283\" data-id=\"41ec283\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a801425 elementor-widget elementor-widget-spacer\" data-id=\"a801425\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9071838 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9071838\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34c0473\" data-id=\"34c0473\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b32b29 elementor-widget elementor-widget-spacer\" data-id=\"8b32b29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4499481 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4499481\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af9ba91\" data-id=\"af9ba91\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efd9780 elementor-widget elementor-widget-heading\" data-id=\"efd9780\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I VANTAGGI DI PRENOTARE UNA CROCIERA A VELA IN GRECIA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91094f8 raven-tabs-mobile-stacking-yes raven-advanced-tab-icon-position-left elementor-widget elementor-widget-raven-tabs\" data-id=\"91094f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;tabs_pane_animation&quot;:&quot;none&quot;,&quot;tabs_event&quot;:&quot;click&quot;,&quot;auto_switch&quot;:&quot;label_off&quot;,&quot;scroll_to_beginning&quot;:&quot;yes&quot;}\" data-widget_type=\"raven-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\">\n\t\t\t<div class=\"raven-tabs raven-tabs-horizontal raven-tabs-card\">\n\t\t\t\t<div class=\"raven-tabs-list\" role=\"tablist\">\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"raven-tabs-title-1521\" class=\"raven-tabs-title raven-tabs-desktop-title raven-tabs-active raven-tabs-has-icon\" role=\"tab\" aria-controls=\"raven-tabs-content-1521\" tabindex=\"-1\" data-tab=\"1\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"raven-tabs-title-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"raven-tabs-title-text\">PROCESSO DI PRENOTAZIONE<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"raven-tabs-title-1522\" class=\"raven-tabs-title raven-tabs-desktop-title raven-tabs-has-icon\" role=\"tab\" aria-controls=\"raven-tabs-content-1522\" tabindex=\"-1\" data-tab=\"2\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"raven-tabs-title-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"raven-tabs-title-text\">PAGAMENTO<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div id=\"raven-tabs-title-1523\" class=\"raven-tabs-title raven-tabs-desktop-title raven-tabs-has-icon\" role=\"tab\" aria-controls=\"raven-tabs-content-1523\" tabindex=\"-1\" data-tab=\"3\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"raven-tabs-title-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"raven-tabs-title-text\">POST CROCIERA<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"raven-tabs-content-wrapper\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"raven-tabs-title raven-tabs-mobile-title raven-tabs-active raven-tabs-has-icon\" role=\"tab\" tabindex=\"-1\" data-tab=\"1\">\n\t\t\t\t\t\t\t<span class=\"raven-tabs-title-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"raven-tabs-title-text\">PROCESSO DI PRENOTAZIONE<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div id=\"raven-tabs-content-1521\" class=\"raven-tabs-content elementor-clearfix raven-tabs-active\" role=\"tabpanel\" aria-labelledby=\"raven-tabs-title-1521\" data-tab=\"1\">\n\t\t\t\t<div class=\"raven-animations-none is-template-content\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"raven-tabs-title raven-tabs-mobile-title raven-tabs-has-icon\" role=\"tab\" tabindex=\"-1\" data-tab=\"2\">\n\t\t\t\t\t\t\t<span class=\"raven-tabs-title-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"raven-tabs-title-text\">PAGAMENTO<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div id=\"raven-tabs-content-1522\" class=\"raven-tabs-content elementor-clearfix\" role=\"tabpanel\" aria-labelledby=\"raven-tabs-title-1522\" data-tab=\"2\">\n\t\t\t\t<div class=\"raven-animations-none is-template-content\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"raven-tabs-title raven-tabs-mobile-title raven-tabs-has-icon\" role=\"tab\" tabindex=\"-1\" data-tab=\"3\">\n\t\t\t\t\t\t\t<span class=\"raven-tabs-title-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"raven-tabs-title-text\">POST CROCIERA<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div id=\"raven-tabs-content-1523\" class=\"raven-tabs-content elementor-clearfix\" role=\"tabpanel\" aria-labelledby=\"raven-tabs-title-1523\" data-tab=\"3\">\n\t\t\t\t<div class=\"raven-animations-none is-template-content\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Prenotazioni di agenti Il nostro obiettivo \u00e8 quello di rendere il lavoro con Sail in Grecia il pi\u00f9 semplice possibile. Crediamo nella trasparenza, nell&#8217;evitare sorprese e nell&#8217;aiutare a definire le aspettative con lei e i suoi clienti. Questo ci permette di prevenire le delusioni e di avere clienti felici a bordo delle nostre navi. CONTATTI [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-37800","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"Prenotazioni di agenti Il nostro obiettivo \u00e8 quello di rendere il lavoro con Sail in Grecia il pi\u00f9 semplice possibile. Crediamo nella trasparenza, nell\u2019evitare sorprese e nell\u2019aiutare a definire le aspettative con lei e i suoi clienti. Questo ci permette di prevenire le delusioni e di avere clienti felici a bordo delle nostre navi. CONTATTI\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"sy88jQLx-_fjDSrygY17DEdpgCjlcvhs9iPMwhgJlh8\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/sail-ingreece.com\/it\/agenti-viaggio\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Sail in Greece\u2122 | Greek Cruises &amp; Sailing Holidays 2025\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Agenti | Sail in Greece\u2122\" \/>\n\t\t<meta property=\"og:description\" content=\"Prenotazioni di agenti Il nostro obiettivo \u00e8 quello di rendere il lavoro con Sail in Grecia il pi\u00f9 semplice possibile. Crediamo nella trasparenza, nell\u2019evitare sorprese e nell\u2019aiutare a definire le aspettative con lei e i suoi clienti. Questo ci permette di prevenire le delusioni e di avere clienti felici a bordo delle nostre navi. CONTATTI\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/sail-ingreece.com\/it\/agenti-viaggio\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/sail-ingreece.com\/wp-content\/uploads\/2025\/03\/DJI_0776-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/sail-ingreece.com\/wp-content\/uploads\/2025\/03\/DJI_0776-scaled.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-02-15T14:03:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-12T06:38:33+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SailinGreeceadventures\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@i\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Agenti | Sail in Greece\u2122\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Prenotazioni di agenti Il nostro obiettivo \u00e8 quello di rendere il lavoro con Sail in Grecia il pi\u00f9 semplice possibile. Crediamo nella trasparenza, nell\u2019evitare sorprese e nell\u2019aiutare a definire le aspettative con lei e i suoi clienti. Questo ci permette di prevenire le delusioni e di avere clienti felici a bordo delle nostre navi. CONTATTI\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@i\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/sail-ingreece.com\/wp-content\/uploads\/2023\/11\/white.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/agenti-viaggio#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/agenti-viaggio#listItem\",\"name\":\"Agenti\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/agenti-viaggio#listItem\",\"position\":2,\"name\":\"Agenti\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/#organization\",\"name\":\"Sail in Greece\\u2122\",\"description\":\"Greek Cruises & Sailing Holidays 2025\",\"url\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/\",\"telephone\":\"+442032399253\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sail-ingreece.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/white.png\",\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/agenti-viaggio\\\/#organizationLogo\",\"width\":300,\"height\":95},\"image\":{\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/agenti-viaggio\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SailinGreeceadventures\\\/\",\"https:\\\/\\\/twitter.com\\\/i\\\/flow\\\/login?redirect_after_login=Sail_inGreece\",\"https:\\\/\\\/www.instagram.com\\\/sail_ingreece\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHxbXUdfpDdapnEEdyCVTyA\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/agenti-viaggio#webpage\",\"url\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/agenti-viaggio\",\"name\":\"Agenti | Sail in Greece\\u2122\",\"description\":\"Prenotazioni di agenti Il nostro obiettivo \\u00e8 quello di rendere il lavoro con Sail in Grecia il pi\\u00f9 semplice possibile. Crediamo nella trasparenza, nell\\u2019evitare sorprese e nell\\u2019aiutare a definire le aspettative con lei e i suoi clienti. Questo ci permette di prevenire le delusioni e di avere clienti felici a bordo delle nostre navi. CONTATTI\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/agenti-viaggio#breadcrumblist\"},\"datePublished\":\"2024-02-15T16:03:20+02:00\",\"dateModified\":\"2026-06-12T08:38:33+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/\",\"name\":\"Sail in Greece\\u2122\",\"description\":\"Greek Cruises & Sailing Holidays 2025\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/sail-ingreece.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Agenti | Sail in Greece\u2122<\/title>\n\n","aioseo_head_json":{"title":"Agenti | Sail in Greece\u2122","description":"Prenotazioni di agenti Il nostro obiettivo \u00e8 quello di rendere il lavoro con Sail in Grecia il pi\u00f9 semplice possibile. Crediamo nella trasparenza, nell\u2019evitare sorprese e nell\u2019aiutare a definire le aspettative con lei e i suoi clienti. Questo ci permette di prevenire le delusioni e di avere clienti felici a bordo delle nostre navi. CONTATTI","canonical_url":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"sy88jQLx-_fjDSrygY17DEdpgCjlcvhs9iPMwhgJlh8","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sail-ingreece.com\/it\/#listItem","position":1,"name":"Home","item":"https:\/\/sail-ingreece.com\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio#listItem","name":"Agenti"}},{"@type":"ListItem","@id":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio#listItem","position":2,"name":"Agenti","previousItem":{"@type":"ListItem","@id":"https:\/\/sail-ingreece.com\/it\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/sail-ingreece.com\/it\/#organization","name":"Sail in Greece\u2122","description":"Greek Cruises & Sailing Holidays 2025","url":"https:\/\/sail-ingreece.com\/it\/","telephone":"+442032399253","logo":{"@type":"ImageObject","url":"https:\/\/sail-ingreece.com\/wp-content\/uploads\/2023\/11\/white.png","@id":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio\/#organizationLogo","width":300,"height":95},"image":{"@id":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/SailinGreeceadventures\/","https:\/\/twitter.com\/i\/flow\/login?redirect_after_login=Sail_inGreece","https:\/\/www.instagram.com\/sail_ingreece\/","https:\/\/www.youtube.com\/channel\/UCHxbXUdfpDdapnEEdyCVTyA"]},{"@type":"WebPage","@id":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio#webpage","url":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio","name":"Agenti | Sail in Greece\u2122","description":"Prenotazioni di agenti Il nostro obiettivo \u00e8 quello di rendere il lavoro con Sail in Grecia il pi\u00f9 semplice possibile. Crediamo nella trasparenza, nell\u2019evitare sorprese e nell\u2019aiutare a definire le aspettative con lei e i suoi clienti. Questo ci permette di prevenire le delusioni e di avere clienti felici a bordo delle nostre navi. CONTATTI","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/sail-ingreece.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio#breadcrumblist"},"datePublished":"2024-02-15T16:03:20+02:00","dateModified":"2026-06-12T08:38:33+02:00"},{"@type":"WebSite","@id":"https:\/\/sail-ingreece.com\/it\/#website","url":"https:\/\/sail-ingreece.com\/it\/","name":"Sail in Greece\u2122","description":"Greek Cruises & Sailing Holidays 2025","inLanguage":"it-IT","publisher":{"@id":"https:\/\/sail-ingreece.com\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Sail in Greece\u2122 | Greek Cruises &amp; Sailing Holidays 2025","og:type":"article","og:title":"Agenti | Sail in Greece\u2122","og:description":"Prenotazioni di agenti Il nostro obiettivo \u00e8 quello di rendere il lavoro con Sail in Grecia il pi\u00f9 semplice possibile. Crediamo nella trasparenza, nell\u2019evitare sorprese e nell\u2019aiutare a definire le aspettative con lei e i suoi clienti. Questo ci permette di prevenire le delusioni e di avere clienti felici a bordo delle nostre navi. CONTATTI","og:url":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio","og:image":"https:\/\/sail-ingreece.com\/wp-content\/uploads\/2025\/03\/DJI_0776-scaled.jpg","og:image:secure_url":"https:\/\/sail-ingreece.com\/wp-content\/uploads\/2025\/03\/DJI_0776-scaled.jpg","article:published_time":"2024-02-15T14:03:20+00:00","article:modified_time":"2026-06-12T06:38:33+00:00","article:publisher":"https:\/\/www.facebook.com\/SailinGreeceadventures\/","twitter:card":"summary_large_image","twitter:site":"@i","twitter:title":"Agenti | Sail in Greece\u2122","twitter:description":"Prenotazioni di agenti Il nostro obiettivo \u00e8 quello di rendere il lavoro con Sail in Grecia il pi\u00f9 semplice possibile. Crediamo nella trasparenza, nell\u2019evitare sorprese e nell\u2019aiutare a definire le aspettative con lei e i suoi clienti. Questo ci permette di prevenire le delusioni e di avere clienti felici a bordo delle nostre navi. CONTATTI","twitter:creator":"@i","twitter:image":"https:\/\/sail-ingreece.com\/wp-content\/uploads\/2023\/11\/white.png"},"aioseo_meta_data":{"post_id":"37800","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-06-12 06:52:50","breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2024-02-19 07:57:23","updated":"2026-06-12 07:47:48"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/sail-ingreece.com\/it\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u203a<\/span><span class=\"aioseo-breadcrumb\">\n\tAgenti\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/sail-ingreece.com\/it\/"},{"label":"Agenti","link":"https:\/\/sail-ingreece.com\/it\/agenti-viaggio"}],"_links":{"self":[{"href":"https:\/\/sail-ingreece.com\/it\/wp-json\/wp\/v2\/pages\/37800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sail-ingreece.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sail-ingreece.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sail-ingreece.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sail-ingreece.com\/it\/wp-json\/wp\/v2\/comments?post=37800"}],"version-history":[{"count":2,"href":"https:\/\/sail-ingreece.com\/it\/wp-json\/wp\/v2\/pages\/37800\/revisions"}],"predecessor-version":[{"id":84330,"href":"https:\/\/sail-ingreece.com\/it\/wp-json\/wp\/v2\/pages\/37800\/revisions\/84330"}],"wp:attachment":[{"href":"https:\/\/sail-ingreece.com\/it\/wp-json\/wp\/v2\/media?parent=37800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}